{"id":1498,"date":"2025-12-04T14:59:17","date_gmt":"2025-12-04T13:59:17","guid":{"rendered":"https:\/\/www.increa.eu\/proeycto\/conducciones-de-la-desaladora-de-valdelentisco-cartagena-murcia-estudio-de-procesos-constructivos-de-las\/"},"modified":"2026-03-13T10:18:42","modified_gmt":"2026-03-13T09:18:42","slug":"conducciones-de-la-desaladora-de-valdelentisco-cartagena-murcia-estudio-de-procesos-constructivos-de-las","status":"publish","type":"proyecto","link":"https:\/\/www.increa.eu\/es\/proyecto\/conducciones-de-la-desaladora-de-valdelentisco-cartagena-murcia-estudio-de-procesos-constructivos-de-las\/","title":{"rendered":"CONDUCCIONES DE LA DESALADORA DE VALDELENTISCO, CARTAGENA, MURCIA. ESTUDIO DE PROCESOS CONSTRUCTIVOS DE LAS"},"featured_media":1499,"parent":0,"template":"","meta":{"_acf_changed":false},"localizacion":[16],"tipo-de-proyecto":[22],"class_list":["post-1498","proyecto","type-proyecto","status-publish","has-post-thumbnail","hentry","localizacion-espana","tipo-de-proyecto-conducciones-submarinas"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/proyecto\/1498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/proyecto"}],"about":[{"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/types\/proyecto"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/media\/1499"}],"wp:attachment":[{"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/media?parent=1498"}],"wp:term":[{"taxonomy":"localizacion","embeddable":true,"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/localizacion?post=1498"},{"taxonomy":"tipo-de-proyecto","embeddable":true,"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/tipo-de-proyecto?post=1498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}