{"id":2106,"date":"2026-01-27T11:35:49","date_gmt":"2026-01-27T10:35:49","guid":{"rendered":"https:\/\/www.increa.eu\/lanzamiento-nueva-web-26-09-2013\/"},"modified":"2026-01-27T11:35:49","modified_gmt":"2026-01-27T10:35:49","slug":"lanzamiento-nueva-web-26-09-2013","status":"publish","type":"post","link":"https:\/\/www.increa.eu\/es\/lanzamiento-nueva-web-26-09-2013\/","title":{"rendered":"Lanzamiento nueva web. 26\/09\/2013"},"content":{"rendered":"<p>Tras varios meses de trabajo, INCREA lanza su nueva web con mejoras sustanciales en la misma, tratando de aportar a sus clientes la m\u00e1xima informaci\u00f3n posible dentro de su \u00e1mbito de especialidad: conducciones submarinas e infraestructuras portuarias.<\/p>\n<p>&nbsp;<\/p>\n<p>Las mejoras en la nueva web son destacadas. Se ha introducido una breve pero detallada descripci\u00f3n dela empresa as\u00ed como de los servicios prestados. Tambi\u00e9n se a\u00f1aden dos apartados que pueden ser de gran utilidad para nuestros clientes: referencias y contenido multimedia.<\/p>\n<p>&nbsp;<\/p>\n<p>En el apartado de referencias se introduce la descripci\u00f3n de&nbsp; los proyectos m\u00e1s importantes llevados a cabo. Estos Proyectos se pueden buscar seg\u00fan los pa\u00edses de ubicaci\u00f3n o bien ordenados por tipolog\u00eda.<\/p>\n<p>&nbsp;<\/p>\n<p>En el apartado multimedia pueden descargarse algunas de las conferencias impartidas por el personal de la empresa, as\u00ed como ver v\u00eddeos de inter\u00e9s as\u00ed como presentaciones power point de las conferencias m\u00e1s importantes.<\/p>\n<p>&nbsp;<\/p>\n<p>Cualquier comentario o sugerencia ser\u00e1 bien recibido, pudi\u00e9ndose poner en contacto a trav\u00e9s del apartado correspondiente.<\/p>\n<p><span style=\"font-family: Calibri; font-size: small;\">&nbsp;<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.increa.eu\/es\/noticias\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras varios meses de trabajo, INCREA lanza su nueva web con mejoras sustanciales en la misma, tratando de aportar a sus clientes la m\u00e1xima informaci\u00f3n posible dentro de su \u00e1mbito de especialidad: conducciones submarinas e infraestructuras portuarias. &nbsp; Las mejoras en la nueva web son destacadas. Se ha introducido una breve pero detallada descripci\u00f3n dela [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-2106","post","type-post","status-publish","format-standard","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/posts\/2106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/comments?post=2106"}],"version-history":[{"count":0,"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/posts\/2106\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/media?parent=2106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/categories?post=2106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/tags?post=2106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}