{"id":2042,"date":"2026-01-27T11:34:46","date_gmt":"2026-01-27T10:34:46","guid":{"rendered":"https:\/\/www.increa.eu\/ponencia-de-eloy-pita-en-la-5a-conferencia-internacional-de-desalacion-que-se-celebra-en-sharm-el-sheikh\/"},"modified":"2026-01-27T11:34:46","modified_gmt":"2026-01-27T10:34:46","slug":"ponencia-de-eloy-pita-en-la-5a-conferencia-internacional-de-desalacion-que-se-celebra-en-sharm-el-sheikh","status":"publish","type":"post","link":"https:\/\/www.increa.eu\/es\/ponencia-de-eloy-pita-en-la-5a-conferencia-internacional-de-desalacion-que-se-celebra-en-sharm-el-sheikh\/","title":{"rendered":"Ponencia de Eloy Pita en la 5\u00aa Conferencia Internacional de Desalaci\u00f3n que se celebra en Sharm El-Sheikh."},"content":{"rendered":"<p><span>Gran \u00e9xito de la ponencia de Eloy Pita en la 5\u00aa Conferencia Internacional de Desalaci\u00f3n que se celebra en Sharm El-Sheikh. La ponencia, titulada \u00abExperiencias recientes de instalaciones marinas para plantas desaladoras en Egipto\u00bb, describe los trabajos marinos de las \u00faltimas plantas desaladoras dise\u00f1adas por INCREA en Egipto: El-Alamein, Negella, Matrouh, Elarish, etc\u00e9tera. Sin duda, una presentaci\u00f3n muy interesante que describe los \u00faltimos trabajos y sus peculiaridades.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.increa.eu\/es\/noticias\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gran \u00e9xito de la ponencia de Eloy Pita en la 5\u00aa Conferencia Internacional de Desalaci\u00f3n que se celebra en Sharm El-Sheikh. La ponencia, titulada \u00abExperiencias recientes de instalaciones marinas para plantas desaladoras en Egipto\u00bb, describe los trabajos marinos de las \u00faltimas plantas desaladoras dise\u00f1adas por INCREA en Egipto: El-Alamein, Negella, Matrouh, Elarish, etc\u00e9tera. Sin duda, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2043,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-2042","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/posts\/2042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/comments?post=2042"}],"version-history":[{"count":0,"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/posts\/2042\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/media\/2043"}],"wp:attachment":[{"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/media?parent=2042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/categories?post=2042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.increa.eu\/es\/wp-json\/wp\/v2\/tags?post=2042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}